{"id":4365,"count":1,"description":"","link":"https:\/\/ic4ml.org\/es\/topics\/accessibility\/","name":"Accessibility","slug":"accessibility","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accessibility - Journal of Media Literacy Articles and Blogs - International Council for Media Literacy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ic4ml.org\/es\/topics\/accessibility\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accessibility - Journal of Media Literacy Articles and Blogs - International Council for Media Literacy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ic4ml.org\/es\/topics\/accessibility\/\" \/>\n<meta property=\"og:site_name\" content=\"International Council for Media Literacy\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/ic4ml.org\/wp-content\/uploads\/2022\/03\/cropped-ic4ml-international-council-for-media-liteacy-square-512-logo.jpg?fit=512%2C512&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@IC4ML\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ic4ml.org\\\/es\\\/topics\\\/accessibility\\\/\",\"url\":\"https:\\\/\\\/ic4ml.org\\\/es\\\/topics\\\/accessibility\\\/\",\"name\":\"Accessibility - Journal of Media Literacy Articles and Blogs - International Council for Media Literacy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ic4ml.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ic4ml.org\\\/es\\\/topics\\\/accessibility\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ic4ml.org\\\/es\\\/topics\\\/accessibility\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ic4ml.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accessibility\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ic4ml.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ic4ml.org\\\/es\\\/\",\"name\":\"International Council for Media Literacy\",\"description\":\"Bridging Academia to Action\",\"publisher\":{\"@id\":\"https:\\\/\\\/ic4ml.org\\\/es\\\/#organization\"},\"alternateName\":\"IC4ML\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ic4ml.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ic4ml.org\\\/es\\\/#organization\",\"name\":\"International Council for Media Literacy\",\"alternateName\":\"IC4ML\",\"url\":\"https:\\\/\\\/ic4ml.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ic4ml.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/ic4ml.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ic4ml-logo-400-px-no-byline.png?fit=400%2C255&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/ic4ml.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ic4ml-logo-400-px-no-byline.png?fit=400%2C255&ssl=1\",\"width\":400,\"height\":255,\"caption\":\"International Council for Media Literacy\"},\"image\":{\"@id\":\"https:\\\/\\\/ic4ml.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IC4ML\",\"https:\\\/\\\/x.com\\\/IC4ML\",\"https:\\\/\\\/www.instagram.com\\\/ICforML\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accessibility - Journal of Media Literacy Articles and Blogs - International Council for Media Literacy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ic4ml.org\/es\/topics\/accessibility\/","og_locale":"es_ES","og_type":"article","og_title":"Accessibility - Journal of Media Literacy Articles and Blogs - International Council for Media Literacy","og_url":"https:\/\/ic4ml.org\/es\/topics\/accessibility\/","og_site_name":"International Council for Media Literacy","og_image":[{"width":512,"height":512,"url":"https:\/\/i0.wp.com\/ic4ml.org\/wp-content\/uploads\/2022\/03\/cropped-ic4ml-international-council-for-media-liteacy-square-512-logo.jpg?fit=512%2C512&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@IC4ML","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ic4ml.org\/es\/topics\/accessibility\/","url":"https:\/\/ic4ml.org\/es\/topics\/accessibility\/","name":"Accessibility - Journal of Media Literacy Articles and Blogs - International Council for Media Literacy","isPartOf":{"@id":"https:\/\/ic4ml.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/ic4ml.org\/es\/topics\/accessibility\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/ic4ml.org\/es\/topics\/accessibility\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ic4ml.org\/es\/"},{"@type":"ListItem","position":2,"name":"Accessibility"}]},{"@type":"WebSite","@id":"https:\/\/ic4ml.org\/es\/#website","url":"https:\/\/ic4ml.org\/es\/","name":"International Council for Media Literacy","description":"Bridging Academia to Action","publisher":{"@id":"https:\/\/ic4ml.org\/es\/#organization"},"alternateName":"IC4ML","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ic4ml.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ic4ml.org\/es\/#organization","name":"International Council for Media Literacy","alternateName":"IC4ML","url":"https:\/\/ic4ml.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ic4ml.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/ic4ml.org\/wp-content\/uploads\/2022\/06\/ic4ml-logo-400-px-no-byline.png?fit=400%2C255&ssl=1","contentUrl":"https:\/\/i0.wp.com\/ic4ml.org\/wp-content\/uploads\/2022\/06\/ic4ml-logo-400-px-no-byline.png?fit=400%2C255&ssl=1","width":400,"height":255,"caption":"International Council for Media Literacy"},"image":{"@id":"https:\/\/ic4ml.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IC4ML","https:\/\/x.com\/IC4ML","https:\/\/www.instagram.com\/ICforML"]}]}},"_links":{"self":[{"href":"https:\/\/ic4ml.org\/es\/wp-json\/wp\/v2\/tags\/4365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ic4ml.org\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ic4ml.org\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ic4ml.org\/es\/wp-json\/wp\/v2\/posts?tags=4365"},{"href":"https:\/\/ic4ml.org\/es\/wp-json\/wp\/v2\/journal-article?tags=4365"},{"href":"https:\/\/ic4ml.org\/es\/wp-json\/wp\/v2\/tribe_events?tags=4365"},{"href":"https:\/\/ic4ml.org\/es\/wp-json\/wp\/v2\/tec_calendar_embed?tags=4365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}